{"id":24,"count":2,"description":"","link":"http:\/\/shidaisai-ncu.com\/74\/category\/%e9%83%a8%e7%bd%b2\/%e5%95%86%e5%ba%97%e8%a1%97\/","name":"\u5546\u5e97\u8857","slug":"%e5%95%86%e5%ba%97%e8%a1%97","taxonomy":"category","parent":18,"meta":[],"_links":{"self":[{"href":"http:\/\/shidaisai-ncu.com\/74\/wp-json\/wp\/v2\/categories\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/shidaisai-ncu.com\/74\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/shidaisai-ncu.com\/74\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/shidaisai-ncu.com\/74\/wp-json\/wp\/v2\/categories\/18"}],"wp:post_type":[{"href":"http:\/\/shidaisai-ncu.com\/74\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}